{"id":1640,"count":1,"description":"","link":"https:\/\/rishikeshdaytour.com\/blog\/tag\/rajaji-tiger-reserve-open-all-year-round\/","name":"Rajaji Tiger Reserve Open All Year Round","slug":"rajaji-tiger-reserve-open-all-year-round","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/rishikeshdaytour.com\/blog\/wp-json\/wp\/v2\/tags\/1640","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/rishikeshdaytour.com\/blog\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/rishikeshdaytour.com\/blog\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/rishikeshdaytour.com\/blog\/wp-json\/wp\/v2\/posts?tags=1640"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}